{"id":190049,"date":"2016-08-25T15:18:37","date_gmt":"2016-08-25T13:18:37","guid":{"rendered":"http:\/\/www.agrarwelt.com\/heizoelpreise\/deutschland\/wetter-deutschneudorf-09548\/"},"modified":"2016-08-25T16:30:51","modified_gmt":"2016-08-25T14:30:51","slug":"heizoelpreise-deutschneudorf-09548","status":"publish","type":"post","link":"https:\/\/www.agrarwelt.com\/heizoelpreise\/heizoelpreise-in-sachsen\/heizoelpreise-deutschneudorf-09548\/","title":{"rendered":"Die Heiz\u00f6lpreise in Deutschneudorf, 09548"},"content":{"rendered":"<p><!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19643],"tags":[20553,20288,20552,7803],"ort":[39385],"bundesland":[],"class_list":["post-190049","post","type-post","status-publish","format-standard","hentry","category-heizoelpreise-in-sachsen","tag-deutschneudorf","tag-erzgebirgskreis","tag-heizoelpreise-in-09548","tag-sachsen","ort-deutschneudorf"],"_links":{"self":[{"href":"https:\/\/www.agrarwelt.com\/heizoelpreise\/wp-json\/wp\/v2\/posts\/190049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrarwelt.com\/heizoelpreise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrarwelt.com\/heizoelpreise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrarwelt.com\/heizoelpreise\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrarwelt.com\/heizoelpreise\/wp-json\/wp\/v2\/comments?post=190049"}],"version-history":[{"count":0,"href":"https:\/\/www.agrarwelt.com\/heizoelpreise\/wp-json\/wp\/v2\/posts\/190049\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.agrarwelt.com\/heizoelpreise\/wp-json\/wp\/v2\/media?parent=190049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrarwelt.com\/heizoelpreise\/wp-json\/wp\/v2\/categories?post=190049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrarwelt.com\/heizoelpreise\/wp-json\/wp\/v2\/tags?post=190049"},{"taxonomy":"ort","embeddable":true,"href":"https:\/\/www.agrarwelt.com\/heizoelpreise\/wp-json\/wp\/v2\/ort?post=190049"},{"taxonomy":"bundesland","embeddable":true,"href":"https:\/\/www.agrarwelt.com\/heizoelpreise\/wp-json\/wp\/v2\/bundesland?post=190049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}